{"id":14948,"date":"2024-07-19T11:50:27","date_gmt":"2024-07-19T09:50:27","guid":{"rendered":"https:\/\/www.stoelting-gruppe.de\/?p=14948"},"modified":"2024-07-19T11:50:27","modified_gmt":"2024-07-19T09:50:27","slug":"stoelting-sorgt-fuer-sicherheit-bei-heim-em","status":"publish","type":"post","link":"https:\/\/www.stoelting-gruppe.de\/es\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/","title":{"rendered":"St\u00f6lting garantiza la seguridad en el Campeonato Europeo en casa"},"content":{"rendered":"<p>Con m\u00e1s de diez partidos internacionales y en seis estadios, St\u00f6lting garantiz\u00f3 la seguridad de miles de aficionados y numerosos futbolistas de \u00e9lite de toda Europa durante el verano futbol\u00edstico alem\u00e1n: en Gelsenkirchen, St\u00f6lting asumi\u00f3 el papel de principal proveedor de servicios de seguridad en el estadio Arena AufSchalke, mientras que en D\u00fcsseldorf, en el Merkur Spielarena, St\u00f6lting se encarg\u00f3 de la seguridad exterior, incluidas las entradas. Hasta 1300 agentes de seguridad estuvieron de servicio por partido en Gelsenkirchen y D\u00fcsseldorf, y con \u00e9xito. Todos los partidos en el estadio Arena AufSchalke y en el Merkur Spielarena de D\u00fcsseldorf se desarrollaron sin incidentes relevantes para la seguridad. Adem\u00e1s de estas intervenciones, St\u00f6lting prest\u00f3 apoyo a corto plazo en Dortmund, Colonia, Hamburgo y Berl\u00edn en el \u00e1mbito de la seguridad, por ejemplo, en la final celebrada en el Estadio Ol\u00edmpico. En Dortmund, St\u00f6lting tambi\u00e9n se encarg\u00f3 de la seguridad en la Friedensplatz durante las retransmisiones p\u00fablicas y el programa marco que las acompa\u00f1aba.<\/p>\n<p>La gran atenci\u00f3n prestada por los equipos de seguridad de St\u00f6lting qued\u00f3 demostrada en un espectacular incidente ocurrido el 26 de junio, cuando un aficionado al f\u00fatbol sorprendi\u00f3 al jugador de la selecci\u00f3n portuguesa Cristiano Ronaldo, que se dirig\u00eda al t\u00fanel de jugadores, saltando desde la tribuna. Un empleado de St\u00f6lting intervino a tiempo. Las grabaciones de v\u00eddeo del incidente dieron la vuelta al mundo a trav\u00e9s de las redes sociales. Incluso la UEFA agradeci\u00f3 personalmente al miembro del personal de seguridad de St\u00f6lting.<\/p>\n<p>El exitoso Campeonato Europeo celebrado en casa quedar\u00e1 especialmente grabado en la memoria de todos los participantes. \u201ePodemos estar orgullosos del balance positivo del Campeonato Europeo. Ha sido realmente un trabajo excepcional por parte de nuestros empleados\u201c, destaca Sebastian Mosbacher, director general de St\u00f6lting.<br \/>\nService Group GmbH.<\/p>\n<p>Aqu\u00ed encontrar\u00e1 m\u00e1s informaci\u00f3n sobre la participaci\u00f3n de St\u00f6lting en el Campeonato Europeo de 2024: <a href=\"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2024\/07\/2024-07-17_Presseinfo_Stoelting_Bilanz_EM_.pdf\" target=\"_blank\" rel=\"noopener\">Ver PDF<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>3600 empleados acreditados, m\u00e1s de diez partidos de la Eurocopa atendidos y intervenciones en seis estadios de toda Alemania: durante el verano futbol\u00edstico alem\u00e1n, St\u00f6lting se encarg\u00f3 de la seguridad de miles de aficionados y numerosos futbolistas de \u00e9lite de toda Europa.<\/p>","protected":false},"author":15,"featured_media":14950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-14948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>St\u00f6lting Service Group &#8211; St\u00f6lting sorgt f\u00fcr Sicherheit bei Heim-EM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stoelting-gruppe.de\/es\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"St\u00f6lting Service Group &#8211; St\u00f6lting sorgt f\u00fcr Sicherheit bei Heim-EM\" \/>\n<meta property=\"og:description\" content=\"3.600 akkreditierte Mitarbeitende, mehr als zehn betreute EM-Spiele und Eins\u00e4tze in sechs Stadien in ganz Deutschland: Im deutschen Fu\u00dfballsommer sorgte St\u00f6lting f\u00fcr die Sicherheit tausender Fans und zahlreicher Spitzen-Fu\u00dfballer aus ganz Europa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stoelting-gruppe.de\/es\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/\" \/>\n<meta property=\"og:site_name\" content=\"St\u00f6lting Service Group\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/StoeltingServiceGroup\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-19T09:50:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2024\/07\/news-19-07-24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"608\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andy Zippert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andy Zippert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/\"},\"author\":{\"name\":\"Andy Zippert\",\"@id\":\"https:\/\/www.stoelting-gruppe.de\/#\/schema\/person\/b46462d559f7c98607eff6fddbcca15c\"},\"headline\":\"St\u00f6lting sorgt f\u00fcr Sicherheit bei Heim-EM\",\"datePublished\":\"2024-07-19T09:50:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/\"},\"wordCount\":278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.stoelting-gruppe.de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2024\/07\/news-19-07-24.jpg\",\"articleSection\":[\"Aktuelles\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/\",\"url\":\"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/\",\"name\":\"St\u00f6lting Service Group &#8211; St\u00f6lting sorgt f\u00fcr Sicherheit bei Heim-EM\",\"isPartOf\":{\"@id\":\"https:\/\/www.stoelting-gruppe.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2024\/07\/news-19-07-24.jpg\",\"datePublished\":\"2024-07-19T09:50:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#primaryimage\",\"url\":\"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2024\/07\/news-19-07-24.jpg\",\"contentUrl\":\"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2024\/07\/news-19-07-24.jpg\",\"width\":608,\"height\":405},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.stoelting-gruppe.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"St\u00f6lting sorgt f\u00fcr Sicherheit bei Heim-EM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.stoelting-gruppe.de\/#website\",\"url\":\"https:\/\/www.stoelting-gruppe.de\/\",\"name\":\"St\u00f6lting Service Group\",\"description\":\"Wir machen. Seit 125 Jahren. Reinigung, Sicherheit, Personal\",\"publisher\":{\"@id\":\"https:\/\/www.stoelting-gruppe.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.stoelting-gruppe.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.stoelting-gruppe.de\/#organization\",\"name\":\"St\u00f6lting Service Group\",\"url\":\"https:\/\/www.stoelting-gruppe.de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.stoelting-gruppe.de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2020\/12\/SSG-Logo.svg\",\"contentUrl\":\"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2020\/12\/SSG-Logo.svg\",\"width\":426,\"height\":80,\"caption\":\"St\u00f6lting Service Group\"},\"image\":{\"@id\":\"https:\/\/www.stoelting-gruppe.de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/StoeltingServiceGroup\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.stoelting-gruppe.de\/#\/schema\/person\/b46462d559f7c98607eff6fddbcca15c\",\"name\":\"Andy Zippert\",\"sameAs\":[\"http:\/\/az-mediendesign.de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"St\u00f6lting Service Group - St\u00f6lting garantiza la seguridad en los Campeonatos Europeos en casa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stoelting-gruppe.de\/es\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/","og_locale":"es_ES","og_type":"article","og_title":"St\u00f6lting Service Group &#8211; St\u00f6lting sorgt f\u00fcr Sicherheit bei Heim-EM","og_description":"3.600 akkreditierte Mitarbeitende, mehr als zehn betreute EM-Spiele und Eins\u00e4tze in sechs Stadien in ganz Deutschland: Im deutschen Fu\u00dfballsommer sorgte St\u00f6lting f\u00fcr die Sicherheit tausender Fans und zahlreicher Spitzen-Fu\u00dfballer aus ganz Europa.","og_url":"https:\/\/www.stoelting-gruppe.de\/es\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/","og_site_name":"St\u00f6lting Service Group","article_publisher":"https:\/\/www.facebook.com\/StoeltingServiceGroup","article_published_time":"2024-07-19T09:50:27+00:00","og_image":[{"width":608,"height":405,"url":"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2024\/07\/news-19-07-24.jpg","type":"image\/jpeg"}],"author":"Andy Zippert","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andy Zippert","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#article","isPartOf":{"@id":"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/"},"author":{"name":"Andy Zippert","@id":"https:\/\/www.stoelting-gruppe.de\/#\/schema\/person\/b46462d559f7c98607eff6fddbcca15c"},"headline":"St\u00f6lting sorgt f\u00fcr Sicherheit bei Heim-EM","datePublished":"2024-07-19T09:50:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/"},"wordCount":278,"commentCount":0,"publisher":{"@id":"https:\/\/www.stoelting-gruppe.de\/#organization"},"image":{"@id":"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2024\/07\/news-19-07-24.jpg","articleSection":["Aktuelles"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/","url":"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/","name":"St\u00f6lting Service Group - St\u00f6lting garantiza la seguridad en los Campeonatos Europeos en casa","isPartOf":{"@id":"https:\/\/www.stoelting-gruppe.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#primaryimage"},"image":{"@id":"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2024\/07\/news-19-07-24.jpg","datePublished":"2024-07-19T09:50:27+00:00","breadcrumb":{"@id":"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#primaryimage","url":"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2024\/07\/news-19-07-24.jpg","contentUrl":"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2024\/07\/news-19-07-24.jpg","width":608,"height":405},{"@type":"BreadcrumbList","@id":"https:\/\/www.stoelting-gruppe.de\/2024\/07\/19\/stoelting-sorgt-fuer-sicherheit-bei-heim-em\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.stoelting-gruppe.de\/"},{"@type":"ListItem","position":2,"name":"St\u00f6lting sorgt f\u00fcr Sicherheit bei Heim-EM"}]},{"@type":"WebSite","@id":"https:\/\/www.stoelting-gruppe.de\/#website","url":"https:\/\/www.stoelting-gruppe.de\/","name":"Grupo de servicios St\u00f6lting","description":"Nosotros lo hacemos. Desde hace 125 a\u00f1os. Limpieza, seguridad, personal.","publisher":{"@id":"https:\/\/www.stoelting-gruppe.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stoelting-gruppe.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.stoelting-gruppe.de\/#organization","name":"Grupo de servicios St\u00f6lting","url":"https:\/\/www.stoelting-gruppe.de\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.stoelting-gruppe.de\/#\/schema\/logo\/image\/","url":"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2020\/12\/SSG-Logo.svg","contentUrl":"https:\/\/www.stoelting-gruppe.de\/wp-content\/uploads\/2020\/12\/SSG-Logo.svg","width":426,"height":80,"caption":"St\u00f6lting Service Group"},"image":{"@id":"https:\/\/www.stoelting-gruppe.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/StoeltingServiceGroup"]},{"@type":"Person","@id":"https:\/\/www.stoelting-gruppe.de\/#\/schema\/person\/b46462d559f7c98607eff6fddbcca15c","name":"Andy Zippert","sameAs":["http:\/\/az-mediendesign.de"]}]}},"_links":{"self":[{"href":"https:\/\/www.stoelting-gruppe.de\/es\/wp-json\/wp\/v2\/posts\/14948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stoelting-gruppe.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stoelting-gruppe.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stoelting-gruppe.de\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stoelting-gruppe.de\/es\/wp-json\/wp\/v2\/comments?post=14948"}],"version-history":[{"count":1,"href":"https:\/\/www.stoelting-gruppe.de\/es\/wp-json\/wp\/v2\/posts\/14948\/revisions"}],"predecessor-version":[{"id":14951,"href":"https:\/\/www.stoelting-gruppe.de\/es\/wp-json\/wp\/v2\/posts\/14948\/revisions\/14951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stoelting-gruppe.de\/es\/wp-json\/wp\/v2\/media\/14950"}],"wp:attachment":[{"href":"https:\/\/www.stoelting-gruppe.de\/es\/wp-json\/wp\/v2\/media?parent=14948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stoelting-gruppe.de\/es\/wp-json\/wp\/v2\/categories?post=14948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stoelting-gruppe.de\/es\/wp-json\/wp\/v2\/tags?post=14948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}